{"id":263762,"date":"2025-12-22T09:25:05","date_gmt":"2025-12-22T17:25:05","guid":{"rendered":"https:\/\/worldimagingnewslatino.com\/?p=263762"},"modified":"2025-12-22T09:25:05","modified_gmt":"2025-12-22T17:25:05","slug":"hp-anuncia-reestructuracion-fuerza-laboral-transformacion-impulsada-ia","status":"publish","type":"post","link":"https:\/\/worldimagingnewslatino.com\/pt\/hp-anuncia-reestructuracion-fuerza-laboral-transformacion-impulsada-ia\/","title":{"rendered":"HP anuncia una reestructuraci\u00f3n de su fuerza laboral como parte de una transformaci\u00f3n impulsada por la inteligencia artificial"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"2d5e3c19-4bc2-4cf2-b108-9b1142ea6af4\" data-testid=\"conversation-turn-2\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"b4ddbe08-dacb-471c-8137-c3ebbff9ccfe\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<h6 class=\"sr-only\">ChatGPT said:<\/h6>\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"dc998ae5-53fb-42a9-bf14-a2d0cd243c46\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:eb9c6bed-222f-4ac2-9e29-67020c5cd650-8\" data-testid=\"conversation-turn-18\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"27d1771b-2d35-497f-bf4f-76d026612d0d\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"0\" data-end=\"440\"><strong>PALO ALTO | California &#8211; Diciembre de 2025 &#8211;<\/strong> <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">HP Inc.<\/span><\/span> anunci\u00f3 un importante plan de reestructuraci\u00f3n que reducir\u00e1 su fuerza laboral global entre 4.000 y 6.000 puestos de trabajo para finales del a\u00f1o fiscal 2028. La iniciativa representa hasta el 10% de la plantilla de la compa\u00f1\u00eda y est\u00e1 dise\u00f1ada para respaldar la estrategia de largo plazo de HP de integrar la inteligencia artificial en todas sus operaciones.<\/p>\n<p data-start=\"442\" data-end=\"859\">Seg\u00fan su CEO, <strong><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Enrique Lores<\/span><\/span><\/strong>, la empresa est\u00e1 \u201credise\u00f1ando los procesos desde cero utilizando IA\u201d, subrayando que esta transici\u00f3n corresponde a un esfuerzo de modernizaci\u00f3n estructural y no a un ejercicio tradicional de reducci\u00f3n de costos. Como parte del plan, HP proyecta alcanzar aproximadamente 1.000 millones de d\u00f3lares en ahorros anualizados en su ritmo operativo para el a\u00f1o fiscal 2028.<\/p>\n<h5 data-start=\"861\" data-end=\"889\">Departamentos m\u00e1s impactados<\/h5>\n<p data-start=\"891\" data-end=\"947\">La reestructuraci\u00f3n afectar\u00e1 principalmente a cargos en:<\/p>\n<ul>\n<li data-start=\"949\" data-end=\"972\">Desarrollo de productos<\/li>\n<li data-start=\"974\" data-end=\"994\">Operaciones internas<\/li>\n<li data-start=\"996\" data-end=\"1014\">Soporte al cliente<\/li>\n<\/ul>\n<h5>Puestos m\u00e1s vulnerables frente a la IA incluyen<\/h5>\n<ul>\n<li data-start=\"1065\" data-end=\"1138\">Funciones de atenci\u00f3n al cliente respaldadas por agentes de IA y chatbots<\/li>\n<li data-start=\"1140\" data-end=\"1215\">Tareas administrativas y de back-office que involucran procesos repetitivos<\/li>\n<li data-start=\"1217\" data-end=\"1327\">Roles de programaci\u00f3n de nivel inicial y aseguramiento de calidad cada vez m\u00e1s apoyados por herramientas de IA<\/li>\n<li data-start=\"1329\" data-end=\"1450\">Posiciones de operaciones internas con alta carga de coordinaci\u00f3n, susceptibles a la automatizaci\u00f3n de procesos digitales<\/li>\n<\/ul>\n<h5 data-start=\"1452\" data-end=\"1476\">Contexto de la industria<\/h5>\n<p data-start=\"1478\" data-end=\"2030\">HP se suma a otras grandes compa\u00f1\u00edas tecnol\u00f3gicas, entre ellas <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Amazon<\/span><\/span>, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Microsoft<\/span><\/span> y <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Google<\/span><\/span>, que han anunciado reducciones de personal en 2025 como parte de reconfiguraciones m\u00e1s amplias impulsadas por la inteligencia artificial. Esta tendencia refleja la creciente presi\u00f3n sobre los modelos operativos tradicionales, a medida que las empresas incrementan sus inversiones en IA para mejorar la productividad, optimizar procesos y acelerar los ciclos de innovaci\u00f3n.<\/p>\n<h5 data-start=\"2032\" data-end=\"2066\">Panorama financiero y de desempe\u00f1o<\/h5>\n<p data-start=\"2068\" data-end=\"2491\">Los resultados trimestrales m\u00e1s recientes de HP superaron las expectativas, con ingresos que alcanzaron los 14.600 millones de d\u00f3lares y un EPS ajustado de 0,93 d\u00f3lares. Sin embargo, su proyecci\u00f3n de utilidades para el a\u00f1o fiscal 2026, estimada entre 2,90 y 3,20 d\u00f3lares por acci\u00f3n, se ubic\u00f3 por debajo de las previsiones de los analistas, reforzando la necesidad de mayor eficiencia operativa y transformaci\u00f3n estrat\u00e9gica.<\/p>\n<h5 data-start=\"2493\" data-end=\"2524\">Recortes anunciados previamente<\/h5>\n<p data-start=\"2526\" data-end=\"2729\" data-is-last-node=\"\" data-is-only-node=\"\">Esta reestructuraci\u00f3n se suma a una fase anterior ejecutada en el a\u00f1o fiscal 2025, durante la cual HP elimin\u00f3 entre 1.000 y 2.000 puestos adicionales como parte de su plan de modernizaci\u00f3n a largo plazo.<\/p>\n<p data-start=\"2292\" data-end=\"2466\"><strong><a href=\"http:\/\/www.hp.com\" target=\"_blank\" rel=\"noopener\">www.hp.com<\/a><\/strong><\/p>\n<p data-start=\"2292\" data-end=\"2466\"><strong><a href=\"https:\/\/worldimagingnews.com\/hp-announces-workforce-restructuring-as-part-of-ai-driven-transformation\/\" target=\"_blank\" rel=\"noopener\">World Imaging News<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<p class=\"sr-only\">ChatGPT said:<span style=\"font-family: 'PT Serif', serif;\">que realmente empodera a nuestros clientes.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ChatGPT said: PALO ALTO | California &#8211; Diciembre de 2025 &#8211; HP Inc. anunci\u00f3 un importante plan de reestructuraci\u00f3n que reducir\u00e1 su fuerza laboral global entre 4.000 y 6.000 puestos&hellip;<\/p>","protected":false},"author":2,"featured_media":263763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[83],"tags":[1303,173],"class_list":["post-263762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personnel","tag-hewlett-packard","tag-hp"],"_links":{"self":[{"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/posts\/263762"}],"collection":[{"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/comments?post=263762"}],"version-history":[{"count":1,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/posts\/263762\/revisions"}],"predecessor-version":[{"id":263764,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/posts\/263762\/revisions\/263764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/media\/263763"}],"wp:attachment":[{"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/media?parent=263762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/categories?post=263762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/pt\/wp-json\/wp\/v2\/tags?post=263762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}