{"id":263416,"date":"2025-09-07T08:32:20","date_gmt":"2025-09-07T15:32:20","guid":{"rendered":"https:\/\/worldimagingnewslatino.com\/?p=263416"},"modified":"2025-09-07T08:32:20","modified_gmt":"2025-09-07T15:32:20","slug":"fujifilm-presento-nuevos-productos-en-fespa-2025","status":"publish","type":"post","link":"https:\/\/worldimagingnewslatino.com\/it\/fujifilm-presento-nuevos-productos-en-fespa-2025\/","title":{"rendered":"Fujifilm present\u00f3 nuevos productos en FESPA 2025."},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"bdc42947-eeee-4dba-9da1-8d09fb3965fa\" data-testid=\"conversation-turn-348\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"c32d1d64-1d71-45e6-9b47-19145c250cda\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<article class=\"text-token-text-primary w-full focus:outline-none scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-testid=\"conversation-turn-632\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ee3bcf72-f0ce-46d9-984c-2f141b38c4c9\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"0\" data-end=\"490\"><strong>BERL\u00cdN | Alemania \u2013 Mayo de 2025 \u2013<\/strong> Fujifilm present\u00f3 tres innovaciones clave para el mercado de impresi\u00f3n en gran formato durante FESPA Berl\u00edn 2025, marcando su regreso a esta feria desde su \u00faltima participaci\u00f3n en 2023. La compa\u00f1\u00eda anunci\u00f3 el lanzamiento comercial de HS3000, una soluci\u00f3n de impresi\u00f3n <em data-start=\"307\" data-end=\"320\">single pass<\/em>, as\u00ed como de Acuity Triton equipada con la tecnolog\u00eda de tinta AQUAFUZE\u2122, y adem\u00e1s exhibi\u00f3 la Acuity Ultra Hybrid Pro con sistema de automatizaci\u00f3n completo.<\/p>\n<h5><strong>Acuity Ultra Hybrid Pro: Alta flexibilidad de producci\u00f3n<\/strong><\/h5>\n<p data-start=\"492\" data-end=\"861\">Acuity Ultra Hybrid Pro fue dise\u00f1ada para negocios de impresi\u00f3n que buscan m\u00e1xima flexibilidad en producciones largas, cortas o incluso ultra cortas, ya sea en soportes r\u00edgidos o en rollo. Gracias a su funci\u00f3n de impresi\u00f3n r\u00e1pida y al sistema integrado para rollos peque\u00f1os, los usuarios pueden alternar f\u00e1cilmente entre distintos formatos sin detener la operaci\u00f3n.<\/p>\n<p data-start=\"863\" data-end=\"1333\">Con tecnolog\u00eda de tinta patentada por Fujifilm, esta impresora garantiza una excelente adhesi\u00f3n sobre diversos sustratos, mientras que su tama\u00f1o de gota de 3.5 picolitros permite obtener impresiones n\u00edtidas con un consumo de tinta reducido. Con un ancho de impresi\u00f3n de 3,3 metros y hasta 32 cabezales Kyocera, ofrece una producci\u00f3n de alta precisi\u00f3n y gran volumen, impulsada por una configuraci\u00f3n de CMYK + Lc Lm W (cian claro, magenta claro y blanco).<\/p>\n<p data-start=\"1335\" data-end=\"1633\">Incluye un sistema de automatizaci\u00f3n robusto que permite operar desde palet a palet con un solo operario, con opciones de automatizaci\u00f3n total o parcial para optimizar velocidad y flujo de trabajo.<\/p>\n<p>La disponibilidad comercial de la Acuity Ultra Hybrid Pro fue anunciada poco despu\u00e9s del evento.<\/p>\n<h5><strong>Fujifilm &amp; Barberan: Soluciones de una sola pasada de la serie HS<\/strong><\/h5>\n<p data-start=\"1635\" data-end=\"2003\">En alianza con Barber\u00e1n, Fujifilm present\u00f3 tambi\u00e9n la nueva plataforma <em data-start=\"1710\" data-end=\"1723\">single pass<\/em> HS Series, orientada a la producci\u00f3n de ultra alto volumen. El modelo HS6000 alcanza velocidades de hasta 6000 m\u00b2\/hora, mientras que el nuevo HS3000 ofrece una alternativa m\u00e1s compacta y rentable, expandiendo las capacidades <em data-start=\"1965\" data-end=\"1978\">single pass<\/em> a un p\u00fablico m\u00e1s amplio.<\/p>\n<p data-start=\"2005\" data-end=\"2407\">La serie HS incorpora cabezales de impresi\u00f3n con resoluci\u00f3n 600 dpi y tama\u00f1o de gota de 5 picolitros, estableciendo un nuevo est\u00e1ndar en calidad y productividad. Con configuraciones modulares que permiten hasta 216 combinaciones posibles, el sistema se adapta a diferentes necesidades, desde alimentaci\u00f3n manual con 600 tableros por hora hasta salida automatizada de 2000 tableros por hora.<\/p>\n<p data-start=\"2409\" data-end=\"2576\">Adem\u00e1s, ofrece m\u00faltiples juegos de tinta para diversas aplicaciones, muchas de ellas sin requerir primer, lo que reduce costos, consumo energ\u00e9tico e impacto ambiental.<\/p>\n<h5><strong>Acuity Triton con tecnolog\u00eda AQUAFUZE<\/strong><\/h5>\n<p data-start=\"2578\" data-end=\"2922\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/worldimagingnews.com\/wp-content\/uploads\/2025\/05\/thumb_acuity-triton_01.jpg\" width=\"345\" height=\"230\" \/>Fujifilm tambi\u00e9n lanz\u00f3 oficialmente su tecnolog\u00eda de tinta AQUAFUZE, resultado de m\u00e1s de una d\u00e9cada de desarrollo. Esta soluci\u00f3n h\u00edbrida combina lo mejor de las tintas UV LED y a base de agua, proporcionando excelente adhesi\u00f3n en distintos medios, secado r\u00e1pido a bajas temperaturas, y sin necesidad de aplicar primer o recubrimiento final.<\/p>\n<p data-start=\"2924\" data-end=\"3142\">Con emisiones de bajo olor, menor consumo energ\u00e9tico y mayor estabilidad en el disparo de tinta, AQUAFUZE representa una alternativa m\u00e1s sostenible y f\u00e1cil de usar frente a las tintas convencionales a base de agua.<\/p>\n<p data-start=\"3144\" data-end=\"3533\">AQUAFUZE se present\u00f3 a trav\u00e9s de la nueva Acuity Triton, una impresora de 1,6 metros de ancho, fabricada en Jap\u00f3n por Mutoh, capaz de imprimir 15 m\u00b2\/hora con secado instant\u00e1neo, lo que permite pasar directamente al acabado sin tiempos de espera. Su eficiencia energ\u00e9tica y dise\u00f1o de bajo mantenimiento la convierten en una soluci\u00f3n ideal para empresas de todos los tama\u00f1os.<\/p>\n<p data-start=\"3535\" data-end=\"3769\">El modelo Triton ser\u00e1 introducido por fases en distintos mercados, seg\u00fan los acuerdos de distribuci\u00f3n vigentes. Fujifilm invit\u00f3 a distribuidores y clientes del segmento de gran formato a interactuar y conocer esta innovaci\u00f3n en FESPA.<\/p>\n<p data-start=\"3771\" data-end=\"4318\" data-is-last-node=\"\" data-is-only-node=\"\"><strong>David Burton<\/strong>, Director de Fujifilm WFIJ Systems, coment\u00f3: \u201cEstamos encantados de regresar a FESPA despu\u00e9s de dos a\u00f1os, con soluciones \u00fanicas para el mercado industrial de se\u00f1alizaci\u00f3n e impresi\u00f3n de gran volumen. Nuestra estrategia de dos stands reflej\u00f3 la diversidad de necesidades de nuestros clientes. En Fujifilm no salimos al mercado apresuradamente: escuchamos, evaluamos y respondemos con tecnolog\u00eda desarrollada con prop\u00f3sito y lista para el futuro. Estas tres nuevas soluciones est\u00e1n llamadas a convertirse en referentes de la industria.\u201d<br \/>\n<strong><a href=\"http:\/\/www.fujifilmprint.eu\" target=\"_blank\" rel=\"noopener\">www.fujifilmprint.eu<\/a><\/strong><br \/>\n<a href=\"https:\/\/worldimagingnews.com\/fujifilm-unveiled-new-products-at-fespa-2025\/\" target=\"_blank\" rel=\"noopener\">World Imagine News<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"aria-live=polite absolute\">\n<div class=\"flex items-center justify-center\"><span class=\"flex items-center gap-1.5 select-none\"><span class=\"sr-only whitespace-nowrap! md:not-sr-only\">Preguntar a ChatGP<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<h6 class=\"sr-only\">ChatGPT said<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<h6 class=\"sr-only\">Mimaki USA announces UJV300DTF-75 printer Purpose-built for UV-DTF (direct-to-film) transfer applications<br \/>\nChatGPT s<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>BERL\u00cdN | Alemania \u2013 Mayo de 2025 \u2013 Fujifilm present\u00f3 tres innovaciones clave para el mercado de impresi\u00f3n en gran formato durante FESPA Berl\u00edn 2025, marcando su regreso a esta&hellip;<\/p>","protected":false},"author":2,"featured_media":263372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[223,807,229],"tags":[702,329,1170,1171],"class_list":["post-263416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aqueous","category-featured-news","category-uv-printers","tag-aquafuze","tag-fujifilm","tag-fujifilm-acuity-triton","tag-hs3000"],"_links":{"self":[{"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/posts\/263416"}],"collection":[{"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/comments?post=263416"}],"version-history":[{"count":1,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/posts\/263416\/revisions"}],"predecessor-version":[{"id":263417,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/posts\/263416\/revisions\/263417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/media\/263372"}],"wp:attachment":[{"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/media?parent=263416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/categories?post=263416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/it\/wp-json\/wp\/v2\/tags?post=263416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}