{"id":263048,"date":"2025-07-07T19:09:08","date_gmt":"2025-07-08T02:09:08","guid":{"rendered":"https:\/\/worldimagingnewslatino.com\/?p=263048"},"modified":"2025-07-07T19:45:13","modified_gmt":"2025-07-08T02:45:13","slug":"epson-anuncia-direct-to-shape","status":"publish","type":"post","link":"https:\/\/worldimagingnewslatino.com\/es\/epson-anuncia-direct-to-shape\/","title":{"rendered":"Epson anuncia el sistema de impresi\u00f3n Direct to Shape que combina cabezales PrecisionCore y robots"},"content":{"rendered":"<h5 data-start=\"305\" data-end=\"437\"><em>Epson presenta su revolucionario sistema de impresi\u00f3n directa a objetos 3D que combina cabezales PrecisionCore y rob\u00f3tica industrial<\/em><\/h5>\n<p data-start=\"439\" data-end=\"1034\"><strong>TOKIO | Jap\u00f3n \u2013 Junio de 2025 \u2013<\/strong> Seiko Epson Corporation (TSE: 6724, &#8220;Epson&#8221;) anunci\u00f3 la exhibici\u00f3n de su innovador Direct to Shape Printing System, una soluci\u00f3n de impresi\u00f3n inkjet dise\u00f1ada para imprimir directamente sobre objetos tridimensionales, durante la feria Automatica que se celebra del 24 al 27 de junio de 2025 en Messe M\u00fcnchen, Alemania. Este evento, considerado la feria l\u00edder mundial en automatizaci\u00f3n inteligente y rob\u00f3tica, marcar\u00e1 la primera presentaci\u00f3n internacional de esta tecnolog\u00eda, que servir\u00e1 como plataforma de lanzamiento para su comercializaci\u00f3n global a gran escala.<\/p>\n<p data-start=\"439\" data-end=\"1034\"><strong>Direct to Shape Printing System\u00a0<\/strong><\/p>\n<p data-start=\"439\" data-end=\"1034\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/corporate.epson\/en\/news\/2025\/img\/250619-1.jpg\" alt=\"Epson Announces Direct to Shape Printing System That Combines PrecisionCore Printheads and Robots (June 19, 2025) | News | Epson\" width=\"350\" height=\"294\" \/><\/p>\n<p data-start=\"1036\" data-end=\"1562\">El Direct to Shape Printing System integra los compactos y precisos cabezales de impresi\u00f3n S800 PrecisionCore de Epson, los m\u00e1s peque\u00f1os de la serie PrecisionCore, junto con un robot industrial de 6 ejes. Gracias a su tama\u00f1o reducido, los cabezales S800 pueden imprimir sobre superficies con curvas, ranuras y formas irregulares. El sistema incorpora adem\u00e1s mecanismos de elevaci\u00f3n independientes que permiten ajustar la altura de los cabezales, logrando as\u00ed una impresi\u00f3n de alta calidad y precisi\u00f3n desde diferentes \u00e1ngulos.<\/p>\n<p data-start=\"1564\" data-end=\"2072\">Esta tecnolog\u00eda digitaliza los procesos tradicionales de impresi\u00f3n anal\u00f3gica, optimizando la manufactura mediante la automatizaci\u00f3n de tareas manuales y un uso m\u00e1s eficiente del espacio. La tecnolog\u00eda inkjet de Epson aplica tinta solo en las \u00e1reas y cantidades necesarias, reduciendo el consumo y el desperdicio de materiales, lo que contribuye a una producci\u00f3n m\u00e1s sostenible. Adem\u00e1s, al eliminar la necesidad de placas o materiales especiales, permite la personalizaci\u00f3n y customizaci\u00f3n de manera rentable.<\/p>\n<p data-start=\"2074\" data-end=\"2469\">El Direct to Shape Printing System est\u00e1 dise\u00f1ado para responder a la demanda de impresi\u00f3n sobre formas 3D en sectores como cascos deportivos e industriales, piezas automotrices tanto interiores como exteriores, electrodom\u00e9sticos, equipos deportivos, accesorios, prendas, y tambi\u00e9n aplicaciones funcionales como sensores impresos con tinta conductiva o recubrimientos de objetos tridimensionales.<\/p>\n<p data-start=\"60\" data-end=\"123\"><strong data-start=\"60\" data-end=\"121\">Caracter\u00edsticas clave del Direct to Shape Printing System<\/strong><\/p>\n<ul>\n<li data-start=\"125\" data-end=\"170\">Impresi\u00f3n precisa y exacta sobre objetos 3D<\/li>\n<li data-start=\"172\" data-end=\"238\">Resoluci\u00f3n de 600 dpi x 600 dpi con cabezales S800 PrecisionCore<\/li>\n<li data-start=\"240\" data-end=\"341\">\u00c1ngulos de impresi\u00f3n flexibles mediante un robot de 6 ejes y mecanismos de elevaci\u00f3n independientes<\/li>\n<li data-start=\"343\" data-end=\"425\">Control de trayectoria precisa y procesamiento de imagen para superficies curvas<\/li>\n<li data-start=\"427\" data-end=\"505\">Soporta hasta 5 colores de tinta (por ejemplo, C\/M\/Y\/K\/Blanco), personalizable<\/li>\n<\/ul>\n<p><strong>Modelo de negocio y alianzas<\/strong><\/p>\n<p data-start=\"2914\" data-end=\"3381\">Epson ha realizado investigaciones y desarrollo continuo en su Inkjet Innovation Lab Fujimi, en la prefectura de Nagano, acumulando conocimiento para esta soluci\u00f3n. La compa\u00f1\u00eda busca alianzas globales para acelerar su despliegue comercial, ofreciendo no solo el hardware, sino soluciones completas que incluyen tintas, procesamiento de im\u00e1genes y soporte postventa. Epson tambi\u00e9n colabora con socios estrat\u00e9gicos para la selecci\u00f3n de tintas y la asistencia operativa.<\/p>\n<p data-start=\"3383\" data-end=\"3659\">A partir de julio de 2025, el sistema expuesto en Automatica se instalar\u00e1 de forma permanente en Epson Deutschland GmbH, creando un entorno para pruebas y validaci\u00f3n sobre sustratos reales de clientes, lo que permitir\u00e1 avanzar en la implementaci\u00f3n pr\u00e1ctica de esta tecnolog\u00eda.<\/p>\n<p data-start=\"3661\" data-end=\"3693\"><a class=\"\" href=\"http:\/\/www.epson.com\" target=\"_new\" rel=\"noopener\" data-start=\"3680\" data-end=\"3693\">www.epson.com<\/a><\/p>\n<p data-start=\"3695\" data-end=\"3735\"><a href=\"https:\/\/worldimagingnews.com\/epson-announces-direct-to-shape-printing-system-that-combines-precisioncore-printheads-and-robots\" target=\"_blank\" rel=\"noopener\">World Imaging News<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Epson presenta su revolucionario sistema de impresi\u00f3n directa a objetos 3D que combina cabezales PrecisionCore y rob\u00f3tica industrial TOKIO | Jap\u00f3n \u2013 Junio de 2025 \u2013 Seiko Epson Corporation (TSE:&hellip;<\/p>\n","protected":false},"author":2,"featured_media":263049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","cybocfi_hide_featured_image":"","iawp_total_views":0,"footnotes":""},"categories":[727,1],"tags":[203,1096],"class_list":["post-263048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3d","category-blog","tag-epson","tag-epson-direct-to-shape-printer"],"_links":{"self":[{"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/posts\/263048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/comments?post=263048"}],"version-history":[{"count":2,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/posts\/263048\/revisions"}],"predecessor-version":[{"id":263051,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/posts\/263048\/revisions\/263051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/media\/263049"}],"wp:attachment":[{"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/media?parent=263048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/categories?post=263048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldimagingnewslatino.com\/es\/wp-json\/wp\/v2\/tags?post=263048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}